{"id":1202,"count":1,"description":"","link":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/","name":"xenoestrogen","slug":"xenoestrogen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>xenoestrogen Archives - The Detox Specialist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"xenoestrogen Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/\" \/>\n<meta property=\"og:site_name\" content=\"The Detox Specialist\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/tag\\\/xenoestrogen\\\/\",\"url\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/tag\\\/xenoestrogen\\\/\",\"name\":\"xenoestrogen Archives - The Detox Specialist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/tag\\\/xenoestrogen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/tag\\\/xenoestrogen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"xenoestrogen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/\",\"name\":\"The Detox Specialist\",\"description\":\"For women who are tired and want to reboot &amp; energize\",\"publisher\":{\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2bb6af31de28b9e8b983c0a935e4f7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2bb6af31de28b9e8b983c0a935e4f7b\",\"name\":\"Sandy Halliday\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Sandy2018Sm.jpg\",\"url\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Sandy2018Sm.jpg\",\"contentUrl\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Sandy2018Sm.jpg\",\"width\":180,\"height\":181,\"caption\":\"Sandy Halliday\"},\"logo\":{\"@id\":\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Sandy2018Sm.jpg\"},\"sameAs\":[\"https:\\\/\\\/thedetoxspecialist.com\\\/blog\",\"https:\\\/\\\/www.facebook.com\\\/DetoxDiet\\\/\",\"https:\\\/\\\/www.pinterest.co.uk\\\/detoxdietnews\\\/\"],\"gender\":\"Female\",\"knowsAbout\":[\"Holistic Nutrition\",\"Health Coaching\"],\"knowsLanguage\":[\"English\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"xenoestrogen Archives - The Detox Specialist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/","og_locale":"en_US","og_type":"article","og_title":"xenoestrogen Archives","og_url":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/","og_site_name":"The Detox Specialist","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/","url":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/","name":"xenoestrogen Archives - The Detox Specialist","isPartOf":{"@id":"https:\/\/thedetoxspecialist.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thedetoxspecialist.com\/blog\/tag\/xenoestrogen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thedetoxspecialist.com\/blog\/"},{"@type":"ListItem","position":2,"name":"xenoestrogen"}]},{"@type":"WebSite","@id":"https:\/\/thedetoxspecialist.com\/blog\/#website","url":"https:\/\/thedetoxspecialist.com\/blog\/","name":"The Detox Specialist","description":"For women who are tired and want to reboot &amp; energize","publisher":{"@id":"https:\/\/thedetoxspecialist.com\/blog\/#\/schema\/person\/f2bb6af31de28b9e8b983c0a935e4f7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thedetoxspecialist.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/thedetoxspecialist.com\/blog\/#\/schema\/person\/f2bb6af31de28b9e8b983c0a935e4f7b","name":"Sandy Halliday","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thedetoxspecialist.com\/blog\/wp-content\/uploads\/2023\/12\/Sandy2018Sm.jpg","url":"https:\/\/thedetoxspecialist.com\/blog\/wp-content\/uploads\/2023\/12\/Sandy2018Sm.jpg","contentUrl":"https:\/\/thedetoxspecialist.com\/blog\/wp-content\/uploads\/2023\/12\/Sandy2018Sm.jpg","width":180,"height":181,"caption":"Sandy Halliday"},"logo":{"@id":"https:\/\/thedetoxspecialist.com\/blog\/wp-content\/uploads\/2023\/12\/Sandy2018Sm.jpg"},"sameAs":["https:\/\/thedetoxspecialist.com\/blog","https:\/\/www.facebook.com\/DetoxDiet\/","https:\/\/www.pinterest.co.uk\/detoxdietnews\/"],"gender":"Female","knowsAbout":["Holistic Nutrition","Health Coaching"],"knowsLanguage":["English"]}]}},"_links":{"self":[{"href":"https:\/\/thedetoxspecialist.com\/blog\/wp-json\/wp\/v2\/tags\/1202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thedetoxspecialist.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thedetoxspecialist.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thedetoxspecialist.com\/blog\/wp-json\/wp\/v2\/posts?tags=1202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}